{"id":103580,"date":"2023-04-29T15:29:54","date_gmt":"2023-04-29T18:29:54","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/indy-define-formato-classificacao-bump-500-milhas-indianapolis-2023\/"},"modified":"2023-04-29T15:57:36","modified_gmt":"2023-04-29T18:57:36","slug":"indy-define-formato-classificacao-bump-500-milhas-indianapolis-2023","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/indy\/indy-define-formato-classificacao-bump-500-milhas-indianapolis-2023\/","title":{"rendered":"Indy define formato de classifica\u00e7\u00e3o e Bump das 500 Milhas de Indian\u00e1polis 2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong>Indy <\/strong>divulgou, na \u00faltima sexta-feira (28), o formato da classifica\u00e7\u00e3o da 107\u00aa edi\u00e7\u00e3o das <strong>500 Milhas de Indian\u00e1polis<\/strong>. A defini\u00e7\u00e3o do grid acontece entre os dias 20 e 21 de maio, enquanto a corrida ser\u00e1 no dia 28. Para esta edi\u00e7\u00e3o, o tradicional Bump, que define a \u00faltima fila do grid e deixar\u00e1 um inscrito de fora, retorna ap\u00f3s a aus\u00eancia em 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A classifica\u00e7\u00e3o come\u00e7ar\u00e1 no s\u00e1bado, 20, com a defini\u00e7\u00e3o dos pilotos do 13\u00ba ao 30\u00ba lugar. Todos os 34 inscritos v\u00e3o para a pista para uma tentativa obrigat\u00f3ria, que engloba os tempos somados de quatro voltas. Depois da primeira tentativa de cada um, os concorrentes poder\u00e3o optar por duas raias para tentar melhorar seus tempos. Na primeira, os pilotos t\u00eam seus tempos anteriores anulados, mas ganham prioridade para voltar ao circuito. J\u00e1 a segunda raia \u00e9 mais segura, e os tempos s\u00f3 contam caso sejam melhores que a marca anterior \u2014 mas eles n\u00e3o v\u00e3o para a pista enquanto a primeira fila ainda tiver carros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A sess\u00e3o come\u00e7ar\u00e1 \u00e0s 12h00 (hor\u00e1rio de <strong>Bras\u00edlia<\/strong>) e ir\u00e1 at\u00e9 as 18h50. Ap\u00f3s este per\u00edodo, os 12 melhores tempos estar\u00e3o classificados para o Fast 12, enquanto do 13\u00ba ao 30\u00ba estar\u00e3o com as suas posi\u00e7\u00f5es de largada na Indy 500 solidificadas. Por fim, do 31\u00ba ao 34\u00ba participar\u00e3o do Bump.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f&nbsp;Inscreva-se nos dois canais do GRANDE PR\u00caMIO no YouTube:&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9OlHEgxoaY6QY6nWPoiqQg?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP<\/a>&nbsp;|&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9csiS6q_C3C0FYhyr1rnFA?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP2<\/a><\/strong><br><strong>\u25b6\ufe0f&nbsp;<a href=\"https:\/\/www.twitch.tv\/grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a o canal do GRANDE PR\u00caMIO na Twitch clicando aqui!<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2019\/05\/20195241341403_Fernando-Alonso_DMa.jpg\" alt=\"\" class=\"wp-image-366570\"\/><figcaption>Bump volta a ser disputado na classifica\u00e7\u00e3o ap\u00f3s um ano de aus\u00eancia e eliminar\u00e1 um dos 34 concorrentes \u00e0 Indy 500, assim como aconteceu com Fernando Alonso em 2019 (Foto: Indy)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A defini\u00e7\u00e3o continua no domingo (21). Das 15h00 \u00e0s 16h00, ser\u00e1 realizado o Fast 12, com tentativas \u00fanicas dos pilotos. A ordem de entrada ser\u00e1 definida pelos tempos da classifica\u00e7\u00e3o geral, no s\u00e1bado, do pior ao melhor. Os seis melhores se classificar\u00e3o para o Fast Six, ao passo que do 7\u00ba ao 12\u00ba ter\u00e3o as suas coloca\u00e7\u00f5es no grid de largada definidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na sequ\u00eancia, das 17h00 \u00e0s 18h00, o Bump. Cada carro ter\u00e1 uma tentativa obrigat\u00f3ria (com tempos somados de quatro voltas) e depois poder\u00e1 voltar para a atividade a fim de melhorar o tempo at\u00e9 o t\u00e9rmino da sess\u00e3o. O \u00faltimo colocado desta etapa est\u00e1 eliminado das 500 Milhas de Indian\u00e1polis, enquanto os outros largar\u00e3o da \u00faltima fila.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, das 18h15 \u00e0s 18h45, ser\u00e1 promovido o Fast Six com tentativas \u00fanicas dos participantes. A ordem de entrada no circuito ser\u00e1 definida pelo Fast 12, do mais lento ao mais r\u00e1pido. Ap\u00f3s as tomadas de tempo dos pilotos, ser\u00e1 definida a pole-position e o grid de largada do 1\u00ba ao 6\u00ba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A edi\u00e7\u00e3o de 2023 da Indy 500 acontecer\u00e1 na semana seguinte \u00e0 classifica\u00e7\u00e3o, no dia 28 de maio. Antes disso, a Indy realiza outra etapa em <strong>Indian\u00e1polis<\/strong>, no dia 13 de maio, no circuito misto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Etapa de 2023 ter\u00e1 a volta do Bump a fim de eliminar um concorrente da corrida das 500 Milhas de Indian\u00e1polis. Confira como ser\u00e1 o formato do fim de semana de classifica\u00e7\u00e3o<\/p>\n","protected":false},"author":0,"featured_media":1000645257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[3],"tags":[2980,5660,1491,28285,93,25977,32514],"42wp_author":[47153],"class_list":["post-103580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indy","tag-500-milhas-indianapolis","tag-classificacao","tag-grande-premio","tag-grandepremio","tag-indy","tag-indy-2023","tag-indy-500-2023","42wp_author-gabriel-pitor"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/103580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=103580"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/103580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000645257"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=103580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=103580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=103580"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=103580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}