{"id":104470,"date":"2023-03-27T09:40:43","date_gmt":"2023-03-27T12:40:43","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/aj-allmendinger-xfinity-series-circuito-das-americas-miguel-paludo\/"},"modified":"2023-03-27T10:03:09","modified_gmt":"2023-03-27T13:03:09","slug":"aj-allmendinger-xfinity-series-circuito-das-americas-miguel-paludo","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/nascar\/aj-allmendinger-xfinity-series-circuito-das-americas-miguel-paludo\/","title":{"rendered":"Allmendinger vence etapa da Xfinity Series no Circuito das Am\u00e9ricas. Paludo \u00e9 13\u00ba"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong>Nascar Xfinity Series<\/strong> realizou sua sexta etapa da temporada 2023 no \u00faltimo s\u00e1bado (25), no <strong>Circuito das Am\u00e9ricas<\/strong>, e <strong>A.J. Allmendinger<\/strong> saiu da pole para vencer a disputa ap\u00f3s cair para o 25\u00ba lugar durante a janela de pit-stops, no meio da corrida. Foi a 11\u00aa vit\u00f3ria do americano em circuitos mistos, sua 16\u00aa na Xfinity Series e a segunda consecutiva no Texas. \u00danico brasileiro do grid, <strong>Miguel<\/strong> <strong>Paludo<\/strong> terminou na 13\u00aa coloca\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar da pole, a vida de Allmendinger n\u00e3o foi nada f\u00e1cil no Texas. O piloto da <strong>Kaulig<\/strong> liderou o primeiro est\u00e1gio da disputa, mas apostou em um pit-stop tardio e viu sua estrat\u00e9gia dar errado. Em 25\u00ba, A.J. passou a escalar o pelot\u00e3o e se colocou em d\u00e9cimo com 15 voltas para o fim, logo antes da \u00faltima relargada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A recupera\u00e7\u00e3o continuou no \u00faltimo est\u00e1gio, e com a ordem de paradas, Allmendinger se viu na sexta coloca\u00e7\u00e3o uma volta depois. Assim, o piloto do carro #10 partiu para cima da concorr\u00eancia e ultrapassou um por um, at\u00e9 disputar a ponta lado a lado com <strong>Sheldon<\/strong> <strong>Creed<\/strong> \u2014 que acabou tocado por A.J., levou a pior e rodou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f&nbsp;<a href=\"https:\/\/www.twitch.tv\/grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a o canal do GRANDE PR\u00caMIO na Twitch clicando aqui!<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2023\/03\/COTA.jpeg\" alt=\"\" class=\"wp-image-665692\"\/><figcaption>O Circuito das Am\u00e9ricas recebeu a Nascar neste fim de semana (Foto: Nascar)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f&nbsp;<a href=\"https:\/\/www.twitch.tv\/grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a o canal do GRANDE PR\u00caMIO na Twitch clicando aqui!<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir da\u00ed, Allmendinger liderou sem maiores problemas, mesmo com a r\u00e1pida aproxima\u00e7\u00e3o de <strong>William<\/strong> <strong>Byron<\/strong> \u2014 que terminou atr\u00e1s do vencedor por apenas <strong>0s8<\/strong>. Miguel Paludo, \u00fanico brasileiro presente na Nascar atualmente, largou na 18\u00aa posi\u00e7\u00e3o e tentou fazer uma corrida de recupera\u00e7\u00e3o, mas n\u00e3o passou do 13\u00ba lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No fim, o top-10 acabou composto por <strong>Allmendinger<\/strong>, <strong>Byron<\/strong>, <strong>Ty<\/strong> <strong>Gibbs<\/strong>, <strong>Sammy<\/strong> <strong>Smith<\/strong>, <strong>Justin<\/strong> <strong>Allgaier<\/strong>, <strong>Daniel<\/strong> <strong>Hemric<\/strong>, <strong>Sam<\/strong> <strong>Mayer<\/strong>, <strong>Josh<\/strong> <strong>Berry<\/strong>, <strong>Sheldon<\/strong> <strong>Creed<\/strong> e <strong>Riley<\/strong> <strong>Herbst<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Austin<\/strong> <strong>Hill<\/strong>, que chegou ao Texas na lideran\u00e7a do campeonato, abandonou ap\u00f3s problemas mec\u00e2nicos, mas segue na ponta \u2014 ainda que a diferen\u00e7a para Herbst tenha ca\u00eddo consideravelmente, de 50 para <strong>15<\/strong> <strong>pontos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale destacar que a etapa do Texas foi respons\u00e1vel por classificar quatro pilotos para concorrerem ao pr\u00eamio de <strong>US$ 100 mil <\/strong>[aproximadamente R$ 523 mil] na pr\u00f3xima etapa, em <strong>Richmond<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como Smith, Allgaier, Hemric e Mayer foram os quatro melhores colocados \u2014 entre os pilotos que disputam a temporada inteira \u2014, o que se sair melhor na pr\u00f3xima etapa leva o pr\u00eamio. A corrida de Richmond est\u00e1 marcada para o pr\u00f3ximo fim de semana, no s\u00e1bado (31).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pole-position, A.J. Allmendinger superou altos e baixos ap\u00f3s cair para a 25\u00aa posi\u00e7\u00e3o e se recuperou para vencer etapa da Nascar Xfinity Series no Circuito das Am\u00e9ricas, no Texas<\/p>\n","protected":false},"author":0,"featured_media":1000665693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[14],"tags":[12757,2614,1587,411,2610,1445],"42wp_author":[47142],"class_list":["post-104470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nascar","tag-circuito-das-americas","tag-cota","tag-miguel-paludo","tag-nascar","tag-texas","tag-xfinity-series","42wp_author-jp-nascimento"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/104470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=104470"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/104470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000665693"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=104470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=104470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=104470"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=104470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}