{"id":109704,"date":"2022-08-20T04:15:00","date_gmt":"2022-08-20T07:15:00","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/nicholas-latifi-utopia-hungria-escapar-fim-melancolico-williams-f1\/"},"modified":"2022-08-19T15:10:18","modified_gmt":"2022-08-19T18:10:18","slug":"nicholas-latifi-utopia-hungria-escapar-fim-melancolico-williams-f1","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/f1\/nicholas-latifi-utopia-hungria-escapar-fim-melancolico-williams-f1\/","title":{"rendered":"Latifi vive utopia na Hungria, mas nem assim deve escapar de fim melanc\u00f3lico na Williams"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"HAMILTON EMPLACA CINCO P\u00d3DIOS SEGUIDOS. VAI VENCER NA F\u00d3RMULA 1 2022?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/bAsMjfc55F8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nicholas Latifi \u00e9 daqueles pilotos que, de alguma forma, sempre ser\u00e3o lembrados na F\u00f3rmula 1. No caso espec\u00edfico do canadense, h\u00e1 quem falar\u00e1 ainda por algum tempo da fa\u00e7anha vista no treino livre 3 da Hungria, este ano, quando o piloto desafiou a l\u00f3gica e colocou a Williams no topo da tabela, com um tempo de volta 0s6 mais r\u00e1pido que o de Charles Leclerc, da Ferrari.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As condi\u00e7\u00f5es n\u00e3o eram t\u00e3o normais assim por causa da chuva, mas todos tiveram a chance de melhorar seus tempos de volta. Max Verstappen, por exemplo, voltou \u00e0 pista e conseguiu melhorar a pr\u00f3pria marca, mas no final, viu o #6 colocar nada menos do que 1s7 sobre seu tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um sonho, e que quase se repetiu no Q1 da classifica\u00e7\u00e3o quando, no \u00faltimo instante, Latifi surpreendeu ao fazer a melhor primeira parcial. Um erro, por\u00e9m, o trouxe de volta \u00e0 cruel realidade: \u00faltima coloca\u00e7\u00e3o na corrida e mais um fim de semana sendo o \u00fanico do grid a n\u00e3o marcar pontos na temporada 2022. Mesmo tendo sido o respons\u00e1vel por colocar a Williams na lideran\u00e7a de um treino na F1 \u2014 algo que n\u00e3o acontecia desde Monza, 2017, com Felipe Massa sendo o mais r\u00e1pido tamb\u00e9m no TL3 \u2014, caminha para um fim melanc\u00f3lico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f\u00a0Inscreva-se nos dois canais do GRANDE PR\u00caMIO no YouTube:\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC9OlHEgxoaY6QY6nWPoiqQg?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC9csiS6q_C3C0FYhyr1rnFA?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP2<\/a><\/strong><br><strong>\u25b6\ufe0f\u00a0<a href=\"https:\/\/www.twitch.tv\/grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a o canal do GRANDE PR\u00caMIO na Twitch clicando aqui!<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2022\/07\/williams-nicholaslatifi-02-afp-1024x683.jpg\" alt=\"\" class=\"wp-image-599781\"\/><figcaption>Nicholas Latifi liderou o TL3 na Hungria em 2022 (Foto: AFP)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Latifi estreou na principal categoria do automobilismo em 2020, no time ingl\u00eas, depois de tr\u00eas temporadas na F\u00f3rmula 2. Na base, depois de dois anos discretos, terminou 2019 como vice-campe\u00e3o, atr\u00e1s apenas de Nyck de Vries. Ainda assim, a ida para a F1 foi providencial gra\u00e7as ao patroc\u00ednio da Sofina Foods, empresa de seu pai, o empres\u00e1rio iraniano Michael Latifi, mas Nicholas foi disposto a apagar o estigma de piloto pagante. A primeira temporada, por\u00e9m, passou em branco: 17 GPs e nenhum ponto marcado \u2014 a Williams, ali\u00e1s, foi a \u00fanica a sair zerada naquele ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No segundo ano de F1, Latifi marcou seus primeiros pontos ao completar o GP da Hungria em s\u00e9timo. Na etapa seguinte, na B\u00e9lgica, a nona coloca\u00e7\u00e3o deu a impress\u00e3o de que as coisas poderiam, enfim, come\u00e7ar a engrenar, mas ficou s\u00f3 nisso. Ao final, foram sete pontos contra 16 do ent\u00e3o companheiro de equipe, George Russell.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2022 veio como mais uma chance para o canadense, enfim, mostrar o seu valor, mas Latifi viu a performance da Williams piorar com as mudan\u00e7as aerodin\u00e2micas do novo regulamento. E n\u00e3o \u00e9 de hoje que os ingleses ostentam o t\u00edtulo de pior carro do grid, por mais novidades que busquem levar para os fins de semana. No geral, a briga sempre ser\u00e1 para n\u00e3o terminar nas \u00faltimas coloca\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Latifi, por\u00e9m, tenta manter o tom otimista na luta para sobreviver na F1, ainda que sua vaga seja uma das mais amea\u00e7adas atualmente. Antes mesmo de Fernando Alonso detonar a bomba na Alpine, a inten\u00e7\u00e3o inicial dos franceses era emprestar o pupilo Oscar Piastri para a base em Grove em 2023, ou mesmo esse ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe sinto pressionado, acho que seria o mesmo para qualquer piloto que n\u00e3o tem contrato para o ano que vem. Acho que a press\u00e3o sempre est\u00e1 ali, independente de eu ter tido grandes performances ou por meu lugar agora, que n\u00e3o \u00e9 onde quero estar. Eu sei o que preciso melhorar, quero melhorar, n\u00e3o estou satisfeito com o jeito que as coisas est\u00e3o agora, ent\u00e3o ficarei feliz em tentar e dar passos para evoluir\u201d, declarou o piloto no fim de semana da F1 no Azerbaij\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A press\u00e3o maior vem do seu pr\u00f3prio lado: Alexander Albon, que com a mesma Williams &#8220;chocha e campenga&#8221;, como diria o meme de Renata Vasconcellos, operou uma fa\u00e7anha ainda maior ao pontuar n\u00e3o somente uma, mas duas vezes. E, em alguns momentos, pontos podem valer mais do que dinheiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Latifi, resta aproveitar as nove corridas finais da temporada para reencontrar a performance vista na Hungria e lutar para sair do zero. Se conseguir\u00e1 igualar o feito do companheiro de equipe e pontuar em mais de uma oportunidade, \u00e9 algo totalmente inimagin\u00e1vel, mas ele mesmo j\u00e1 mostrou que milagres acontecem. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEIA TAMB\u00c9M<br>Williams<a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/williams-brilharecos-individuais-ainda-presa-ancora-potente-2022\/\" class=\"ek-link\"> tem \u2018brilharecos\u2019 individuais, mas se v\u00ea ainda presa \u00e0 \u00e2ncora potente em 2022<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dinheiro n\u00e3o \u00e9 tudo, j\u00e1 diz o ditado, e \u00e0s vezes, pontos podem ser mais valiosos numa F\u00f3rmula 1 t\u00e3o concorrida. Nicholas Latifi sabe, portanto, que o fim do sonho na elite do automobilismo mundial pode estar pr\u00f3ximo<\/p>\n","protected":false},"author":0,"featured_media":1000594361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[2],"tags":[1357,24837,1647,801,30986,215],"42wp_author":[47147],"class_list":["post-109704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f1","tag-f1-2022","tag-formula-1-2","tag-gp-da-hungria","tag-nicholas-latifi","tag-temporada-2022-f1","tag-williams","42wp_author-luana-marino"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/109704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=109704"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/109704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000594361"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=109704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=109704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=109704"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=109704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}