{"id":109828,"date":"2022-08-14T04:15:00","date_gmt":"2022-08-14T07:15:00","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/alphatauri-se-perde-desenvolvimento-tardio-erra-rivais-crescerem-2022\/"},"modified":"2022-08-13T16:41:31","modified_gmt":"2022-08-13T19:41:31","slug":"alphatauri-se-perde-desenvolvimento-tardio-erra-rivais-crescerem-2022","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/f1\/alphatauri-se-perde-desenvolvimento-tardio-erra-rivais-crescerem-2022\/","title":{"rendered":"AlphaTauri se perde em desenvolvimento tardio, erra e v\u00ea rivais crescerem em 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A bem da verdade \u00e9 que o projeto da AlphaTauri para 2022 nasceu chocho, capenga, an\u00eamico e tudo mais daquele famoso meme de Renata Vasconcelos. N\u00e3o \u00e9 exagero. A esperan\u00e7a de um salto de qualidade diante de um novo regulamento caiu por terra logo nos primeiros quil\u00f4metros de testes. O AT03 apresentou defici\u00eancias graves e de dif\u00edcil solu\u00e7\u00e3o, sobretudo em fun\u00e7\u00e3o do cr\u00f4nico porpoising. Mais tarde, tamb\u00e9m se descobriu outros problemas t\u00e9cnicos que acentuaram a dificuldade do time em somar pontos, al\u00e9m de diversos equ\u00edvocos que desviaram a equipe italiana de uma posi\u00e7\u00e3o mais \u00e0 frente na tabela. E no topo de tudo, est\u00e1 o demorado pacote de atualiza\u00e7\u00f5es que acabou por minar qualquer chance de escalar o pelot\u00e3o no fim da primeira fase da temporada da F\u00f3rmula 1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O modelo criado pela esquadra de Faenza, dentro das regras que trouxeram de volta o efeito-solo, enfrentou inicialmente o impacto dos quiques. Assim como a Mercedes, o carro branco e azul tamb\u00e9m saltava demais e obrigava os engenheiros a elevar o assoalho, como medida para amenizar os pulos. S\u00f3 que essa manobra tamb\u00e9m causa uma queda da efici\u00eancia aerodin\u00e2mica, um problema que perseguiu a equipe durante boa parte do campeonato. Tamb\u00e9m como consequ\u00eancia, a configura\u00e7\u00e3o do carro provocou um enorme desgaste dos pneus, e isso foi letal em classifica\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Muitas vezes, at\u00e9 consigo fazer uma volta boa, dependendo da ader\u00eancia do pneu novo, mas depois de cinco voltas escorrego cada vez mais, e isso em corrida significa que seus advers\u00e1rios v\u00e3o embora. \u00c9 um pouco frustrante porque no ano passado tivemos uma temporada fant\u00e1stica, e eu estava muito otimista antes de 2022, considerando a mudan\u00e7a de regulamento e o teto or\u00e7ament\u00e1rio, mas est\u00e1 sendo muito pior do que esper\u00e1vamos&#8221;, reconheceu Pierre Gasly em entrevista \u00e0 vers\u00e3o italiana do site Motorsport.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEIA TAMB\u00c9M<br><a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/haas-acerta-repatriar-kevin-magnussen-ve-mick-schumacher-crescer-sobrevive-f1-2022\/\" class=\"ek-link\">+Haas acerta ao repatriar Magnussen, v\u00ea Schumacher crescer e sobrevive na F1 2022<\/a><br><a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/mclaren-alinha-exercito-pilotos-piora-pista-joga-estabilidade-lixo\/\" class=\"ek-link\">+McLaren alinha ex\u00e9rcito de pilotos, mas piora na pista e joga estabilidade no lixo<\/a><br><a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/yuki-tsunoda-passa-longe-evolucao-repete-2021-erros-descontrole\/\" class=\"ek-link\">+Tsunoda desperdi\u00e7a cartas na manga e repete 2021 com erros e descontrole<\/a><br><a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/esteban-ocon-lider-alpine-uracao-2022-prova-posicao-merecida\/\" class=\"ek-link\">+Ocon vira \u2018l\u00edder\u2019 da Alpine em meio ao furac\u00e3o, mas 2022 prova que posi\u00e7\u00e3o \u00e9 merecida<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2022\/07\/alphatauri-pierregasly-02-9-1024x683.jpg\" alt=\"\" class=\"wp-image-599422\"\/><figcaption>Pierre Gasly \u00e9 o respons\u00e1vel pela maior parte dos pontos da AlphaTauri em 2022 (Foto: AlphaTauri)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Quer dizer, sem um comportamento regular dos pneus em um carro desequilibrado, a AlphaTauri perdeu uma de suas melhores qualidades at\u00e9 o ano passado: a performance durante a defini\u00e7\u00e3o do grid de largada. Se antes Gasly conseguia registrar tempos competitivos para avan\u00e7ar \u00e0s fases mais decisivas, neste ano o franc\u00eas ficou vendido. Isso porque \u00e9 necess\u00e1rio sempre um jogo a mais para tentar escalar a sess\u00e3o mais importante do fim de semana. Dessa forma, n\u00e3o foi raro notar Gasly e tamb\u00e9m Yuki Tsunoda quase sempre na parte de baixo da tabela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Uma das raz\u00f5es para a nossa temporada est\u00e1 ligada \u00e0 perda de competitividade na classifica\u00e7\u00e3o, uma frente em que est\u00e1vamos indo muito, muito bem no ano passado. Eu estava constantemente no Q3. E no Q1 eu s\u00f3 precisava de um jogo de pneus para passar, e esse \u00e9 o primeiro motivo que nos afetou neste ano, ou seja, n\u00e3o somos competitivos o suficiente na classifica\u00e7\u00e3o, e isso torna as corridas dif\u00edceis&#8221;, confirmou Pierre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o h\u00e1 muita d\u00favida sobre isso, de fato. Come\u00e7ar do fundo do grid \u00e9 sempre um risco e \u00e9 onde mais se fica sujeito a todo o tipo de sorte. Gasly, inclusive, se viu nesse cen\u00e1rio algumas vezes \u2013 como na Espanha e na \u00c1ustria. Mas h\u00e1 outros motivos que explicam a queda de rendimento do time comandado por Franz Tost. Diferentemente do ano passado, quando ap\u00f3s 13 corridas, a esquadra somava 84 pontos e surgia em sexto, o 2022 tem sido amargo: oitavo posto, s\u00f3 \u00e0 frente de Aston Martin e Williams, al\u00e9m de 27 tentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m de ter de lidar com uma degrada\u00e7\u00e3o consider\u00e1vel dos pneus, o AT03 possui uma falta de downforce em alta velocidade que tira da equipe a chance de progredir no grid. E essa foi uma falha que o grande pacote de atualiza\u00e7\u00f5es visto na Fran\u00e7a \u2013 sim, a AlphaTauri levou 12 etapas at\u00e9 promover mudan\u00e7as significativas \u2013 tentou corrigir, mas sem muito sucesso. Ent\u00e3o, tamb\u00e9m se pode dizer que esse desenvolvimento tardio teve papel crucial no resultado ao fim dessa primeira fase de temporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f\u00a0Inscreva-se nos dois canais do GRANDE PR\u00caMIO no YouTube:\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC9OlHEgxoaY6QY6nWPoiqQg?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC9csiS6q_C3C0FYhyr1rnFA?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP2<\/a><\/strong><br><strong>\u25b6\ufe0f\u00a0<a href=\"https:\/\/www.twitch.tv\/grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a o canal do GRANDE PR\u00caMIO na Twitch clicando aqui!<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"COMO DRUGOVICH VAI FREAR POURCHAIRE NA DISPUTA PELO T\u00cdTULO DA F\u00d3RMULA 2 2022?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/IaQegxn9NG0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Em que pese esses problemas, o carro italiano tem l\u00e1 seus pontos fortes: a ader\u00eancia mec\u00e2nica \u00e9 um deles. Ainda que seja um modelo lento em curvas, o AT03 se deu bem em trechos de baixa velocidade \u2013 em M\u00f4naco e, principalmente, no Azerbaij\u00e3o, onde Gasly foi o sexto no grid e completou a prova na quinta posi\u00e7\u00e3o. O melhor resultado at\u00e9 aqui.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar disso, a equipe seguiu fracassando em outros aspectos que pesaram na performance geral. E a  confiabilidade representa grande parte deste d\u00e9ficit de pontos, por exemplo. No Bahrein, apesar do oitavo lugar de Tsunoda, Pierre abandonou por falha no motor. Na Ar\u00e1bia Saudita, o japon\u00eas sofreu com problemas hidr\u00e1ulicos durante todo o fim de semana e, antes mesmo da corrida, na volta de sa\u00edda dos boxes para o grid, teve de recolher por conta da unidade de pot\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em Miami, o franc\u00eas quebrou de novo, mais uma vez enquanto estava na zona de pontua\u00e7\u00e3o. J\u00e1 Tsunoda reclamou de falta de ader\u00eancia, saindo zerado. Em Barcelona, a trag\u00e9dia aconteceu antes mesmo da corrida: Gasly sofreu com mais uma quebra, dessa vez nos treinos livres, e andou com um carro visivelmente longe das condi\u00e7\u00f5es ideais. Em Baku, o piloto nip\u00f4nico sofreu uma inexplic\u00e1vel falha na asa traseira, que o tirou dos pontos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E como desgra\u00e7a pouca \u00e9 bobagem, a AlphaTauri tamb\u00e9m protagonizou erros de opera\u00e7\u00e3o e estrat\u00e9gia. O equ\u00edvoco mais grave aconteceu em M\u00f4naco, durante a primeira parte da classifica\u00e7\u00e3o. Os engenheiros calcularam mal o tempo para a sa\u00edda dos boxes, e Gasly acabou caindo no Q1. Mas houve problemas no Canad\u00e1, na Em\u00edlia-Romanha e na Inglaterra. Escolhas err\u00f4neas de pneus, bem como de a\u00e7\u00e3o nos pit-stops. \u00c9 bem verdade que os pilotos contribu\u00edram, sobretudo Tsunoda, que chegou a colidir com Gasly em Silverstone. Mesmo assim, a balan\u00e7a cai mais para o lado da equipe.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Paddockast #160 | Piastri, Ricciardo e o restante do grid da F\u00f3rmula 1 2023\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/7qIzgu52oQm7vSq2FKSmFB?si=SFndi5h7R_ePa13xy3pFnA&amp;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Este ano a situa\u00e7\u00e3o \u00e9 muito diferente e, al\u00e9m de n\u00e3o sermos muito competitivos, tivemos v\u00e1rios problemas com o carro, at\u00e9 coisas est\u00fapidas, como o fundo que quebra nas voltas pr\u00e9-grid ou durante a corrida, depois contatos, acidentes, falhas mec\u00e2nicas, problemas com os freios, at\u00e9 mesmo um incidente na classifica\u00e7\u00e3o em M\u00f4naco que me fez perder o giro final, muitas pequenas coisas que afetam todo o fim de semana&#8221;, reconheceu Gasly.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u00c0s vezes, foi poss\u00edvel levar alguns pontos para casa, mas se voc\u00ea come\u00e7a do fundo do grid sempre arrisca muito na primeira curva, se exp\u00f5e a imprevistos e, neste aspecto, isso se reflete no resultado. Mesmo com o carro deste ano, que n\u00e3o \u00e9 t\u00e3o bom quanto o da temporada passada&#8221;, completou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, \u00e9 certo dizer que, tal como a Ferrari, a AlphaTauri se colocou como inimiga de si pr\u00f3pria. E ter\u00e1 uma segunda fase de temporada ainda mais trabalhosa, diante da posi\u00e7\u00e3o em que se encontra. Al\u00e9m de fazer as atualiza\u00e7\u00f5es funcionarem, a equipe italiana ter\u00e1 de enfrentar equipes que vivem um salto de qualidade, como a Haas, Alfa Romeo e Alpine. \u00c9 uma corrida contra um tempo que o time de Faenza j\u00e1 n\u00e3o tem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEIA MAIS<br><a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/formula-1-2022-abaixo-media-mesmo-2021-espetacular-afeta-opiniao\/\" class=\"ek-link\">+F\u00f3rmula 1 2022 est\u00e1 abaixo da m\u00e9dia mesmo ou 2021 espetacular afeta opini\u00e3o?<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AlphaTauri despencou no pelot\u00e3o intermedi\u00e1rio em uma primeira metade de temporada desastrosa em 2022. A equipe de Faenza demorou a atualizar o seu AT03 e cometeu erros demais ao longo das 13 corridas iniciais. Foram equ\u00edvocos de toda a sorte, como opera\u00e7\u00e3o, estrat\u00e9gia e confiabilidade. Por isso, se v\u00ea \u00e0 frente somente de Aston Martin e Williams<\/p>\n","protected":false},"author":0,"featured_media":1000600511,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[2],"tags":[524,1357,24837,25081,1117,1645,676,4210,597],"42wp_author":[47115],"class_list":["post-109828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f1","tag-alphatauri","tag-f1-2022","tag-formula-1-2","tag-horarios-da-f1-2","tag-mundial-de-construtores","tag-mundial-de-pilotos","tag-pierre-gasly","tag-temporada-2022","tag-yuki-tsunoda","42wp_author-evelyn-guimaraes"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/109828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=109828"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/109828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000600511"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=109828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=109828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=109828"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=109828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}