{"id":110760,"date":"2022-07-09T09:47:32","date_gmt":"2022-07-09T12:47:32","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/ferrari-assume-jogo-equipe-charles-leclerc-carlos-sainz-bater-max-verstappen\/"},"modified":"2022-07-09T11:24:54","modified_gmt":"2022-07-09T14:24:54","slug":"ferrari-assume-jogo-equipe-charles-leclerc-carlos-sainz-bater-max-verstappen","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/f1\/ferrari-assume-jogo-equipe-charles-leclerc-carlos-sainz-bater-max-verstappen\/","title":{"rendered":"Ferrari j\u00e1 assume jogo de equipe para bater Verstappen: &#8220;Mais r\u00e1pido ser\u00e1 priorizado&#8221;"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"F1 2022: VERSTAPPEN \u00c9 POLE, HAMILTON E RUSSELL BATEM NA \u00c1USTRIA | Briefing\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/zLL3PJIhvh0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durou pouco o discurso de igualdade de chances entre Charles Leclerc e Carlos Sainz dentro da Ferrari na disputa pelo t\u00edtulo da temporada 2022 da F\u00f3rmula 1. Com Max Verstappen 43 pontos \u00e0 frente do monegasco na classifica\u00e7\u00e3o, Mattia Binotto admitiu que n\u00e3o vai demorar muito para a Ferrari come\u00e7ar a priorizar nas corridas o piloto que estiver na frente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O comportamento da Ferrari com sua dupla de pilotos foi muito questionado principalmente depois da estrat\u00e9gia atrapalhada que novamente custou n\u00e3o s\u00f3 a vit\u00f3ria, como o p\u00f3dio a Leclerc. Na Inglaterra, durante o safety-car provocado por Esteban Ocon na parte final da corrida, a equipe italiana optou por levar aos boxes apenas Sainz para colocar pneus macios, deixando o #16 na pista com compostos duros e desgastados. Leclerc, que vinha em primeiro, se tornou presa f\u00e1cil aos advers\u00e1rios e, mesmo depois de muito lutar, cruzou a linha de chegada em quarto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f\u00a0Inscreva-se nos dois canais do GRANDE PR\u00caMIO no YouTube:\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC9OlHEgxoaY6QY6nWPoiqQg?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC9csiS6q_C3C0FYhyr1rnFA?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP2<\/a><\/strong><br><strong>\u25b6\ufe0f\u00a0<a href=\"https:\/\/www.twitch.tv\/grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a o canal do GRANDE PR\u00caMIO na Twitch clicando aqui!<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2022\/06\/ferrari-charlesleclerc-03-1-1024x683.jpg\" alt=\"\" class=\"wp-image-587215\"\/><figcaption>Leclerc, no momento, est\u00e1 \u00e0 frente de Sainz na classifica\u00e7\u00e3o (Foto: Ferrari)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sainz, com isso, conquistou a sua primeira vit\u00f3ria na F1 e somou pontos importantes, chegando a 127 na tabela. Mas Binotto j\u00e1 avisou que a briga pelo t\u00edtulo n\u00e3o deve ser entre sua dupla, uma vez que isso pode prejudicar a Ferrari no Mundial de Construtores. &#8220;Primeiro, o que tentamos fazer em cada corrida foi maximizar os pontos da equipe&#8221;, disse o italiano \u00e0 Sky Sports.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;S\u00e3o dois campeonatos, e maximizando pontos da equipe, tenho certeza de que tamb\u00e9m estamos potencializando as oportunidades dos pilotos, tirando pontos dos advers\u00e1rios. E os advers\u00e1rios entre si n\u00e3o devem ser Charles e Carlos, e sim Max, Lewis [Hamilton] e outros&#8221;, ressaltou. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;O carro mais r\u00e1pido na pista ser\u00e1 priorizado. Certamente, \u00e9 a melhor coisa a se fazer nesse momento do campeonato. Se mais para frente, um dos dois tiver mais oportunidades, certamente tentaremos dar a ele prioridade total. Mas n\u00e3o \u00e9 a situa\u00e7\u00e3o agora. Portanto, teremos de lidar com isso&#8221;, completou o chefe da equipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEIA MAIS<br>Classifica\u00e7\u00e3o na \u00c1ustria <a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/classificacao-na-austria-iguala-forcas-e-promete-duelo-quente-entre-red-bull-e-ferrari\/\" class=\"ek-link\">iguala for\u00e7as e promete duelo quente entre<\/a> Red Bull e Ferrari<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As decis\u00f5es tomadas no GP da Inglaterra prejudicaram bastante Leclerc, que n\u00e3o escondeu a frustra\u00e7\u00e3o em perder mais uma corrida na estrat\u00e9gia de pit-stop \u2014 o mesmo aconteceu em M\u00f4naco. Por\u00e9m, o piloto rejeitou qualquer ind\u00edcio de crise nos boxes de Maranello, dizendo, inclusive, que todos est\u00e3o &#8220;extremamente unidos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Binotto reconheceu que era bom ver a dupla competitiva nas corridas, mas refor\u00e7ou que a prioridade sempre ser\u00e1 o que for melhor para a Ferrari. &#8220;Sei que quando h\u00e1 ordens de equipe, todo mundo nos culpa porque temos de deix\u00e1-los brigar, mas quando eles ficam livres para isso, falam que deve haver ordens de equipe. O que quer que fa\u00e7amos est\u00e1 sempre errado.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Lembro-me de 20 anos atr\u00e1s, aqui na \u00c1ustria, ter ouvido as vaias da arquibancada. Eu estava aqui&#8221;, acrescentou, referindo-se \u00e0 controversa vit\u00f3ria de Michael Schumacher em 2002, quando Rubens Barrichello teve de ceder posi\u00e7\u00e3o para o alem\u00e3o quando liderava, e a ordem foi cumprida praticamente em cima da linha de chegada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Mais uma vez, o que estamos tentando fazer \u00e9 potencializar os pontos da equipe, que \u00e9 o certo a ser feito&#8221;, concluiu Binotto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mattia Binotto disse que o foco \u00e9 maximizar os pontos da Ferrari no Mundial 2022 da F1. Diante disso, Charles Leclerc e Carlos Sainz &#8220;n\u00e3o podem brigar entre si&#8221;<\/p>\n","protected":false},"author":0,"featured_media":1000574573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[2],"tags":[546,209,1357,207,3554,442,203,1117,1645,30986],"42wp_author":[47147],"class_list":["post-110760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f1","tag-carlos-sainz","tag-charles-leclerc","tag-f1-2022","tag-ferrari","tag-jogo-de-equipe","tag-mattia-binotto","tag-max-verstappen","tag-mundial-de-construtores","tag-mundial-de-pilotos","tag-temporada-2022-f1","42wp_author-luana-marino"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/110760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=110760"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/110760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000574573"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=110760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=110760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=110760"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=110760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}