{"id":117275,"date":"2021-10-04T08:56:54","date_gmt":"2021-10-04T11:56:54","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/mick-schumacher-discorda-de-chefe-e-ve-como-desnecessario-piloto-reserva-experiente-na-haas\/"},"modified":"2021-10-04T08:58:52","modified_gmt":"2021-10-04T11:58:52","slug":"mick-schumacher-discorda-de-chefe-e-ve-como-desnecessario-piloto-reserva-experiente-na-haas","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/f1\/mick-schumacher-discorda-de-chefe-e-ve-como-desnecessario-piloto-reserva-experiente-na-haas\/","title":{"rendered":"Schumacher discorda de chefe e v\u00ea como &#8220;desnecess\u00e1rio&#8221; reserva experiente na Haas"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"&amp;apos;VALTTERI, IT&amp;apos;S MAX!&amp;apos; RED BULL CUTUCA MERCEDES E HORNER ADMITE QUE CURTE PROVOCAR WOLFF\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/3HaJ1r0sU3Y?start=138&amp;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Chefe de equipe da Haas, \u00fanico time da F\u00f3rmula 1 que ainda n\u00e3o conseguiu pontuar em 2021, <a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/haas-revela-busca-piloto-reserva-experiente-para-ser-referencia-interna-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Guenther Steiner j\u00e1 havia falado sobre a possibilidade de contratar um piloto reserva com mais experi\u00eancia para 2022<\/a>, como forma de ajudar a escuderia a desenvolver melhor o carro pelos pr\u00f3ximos anos. No entanto, Mick Schumacher e Nikita Mazepin, titulares da equipe e <a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/haas-anuncia-manutencao-mick-schumacher-nikita-mazepin-2022-apesar-rusgas\/\" target=\"_blank\" rel=\"noreferrer noopener\">confirmados para o ano que vem<\/a>, diferem na opini\u00e3o sobre o assunto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Honestamente, acho que n\u00f3s estamos extraindo o melhor poss\u00edvel do carro&#8221;, disse Schumacher, em entrevista veiculada pela revista brit\u00e2nica Autosport, quando perguntado se um piloto experiente na reserva poderia ajudar no desenvolvimento do b\u00f3lido. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2021\/09\/haas-mickschumacher-02-6-1024x682.jpg\" alt=\"\" class=\"wp-image-512658\"\/><figcaption>Mick Schumacher entende que um reserva experiente n\u00e3o \u00e9 crucial para a evolu\u00e7\u00e3o da Haas (Foto: Haas)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;N\u00e3o acho que tenha necessidade disso. Especialmente porque pilotos reservas n\u00e3o pilotam com muita frequ\u00eancia. N\u00e3o sabemos como seria, mas acho que estamos fazendo o melhor poss\u00edvel e acho que algumas classifica\u00e7\u00f5es mostram que estamos conseguindo extrair o m\u00e1ximo do carro&#8221;, encerrou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seu companheiro de equipe, Nikita Mazepin, escolheu outro caminho. O russo afirmou que poderia ser uma vantagem para a equipe, mas que a decis\u00e3o n\u00e3o pertence aos pilotos, mas sim \u00e0 chefia. No entanto, o novato se mostrou aberto \u00e0 possibilidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Essa quest\u00e3o nunca me foi perguntada [dentro da equipe]&#8221;, disse. &#8220;N\u00e3o acho que os pilotos devam escolher, n\u00e3o acho certo. Mas se me perguntarem, diria que qualquer ajuda na posi\u00e7\u00e3o em que estamos agora seria boa. Ent\u00e3o, estaria aberto a qualquer solu\u00e7\u00e3o. Mas Guenther \u00e9 o chefe, ele que toma essas decis\u00f5es. N\u00e3o eu, sou muito novo para isso&#8221;, opinou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f&nbsp;Inscreva-se nos dois canais do GRANDE PR\u00caMIO no YouTube:&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9OlHEgxoaY6QY6nWPoiqQg?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP<\/a>&nbsp;|&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9csiS6q_C3C0FYhyr1rnFA?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP2<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2021\/09\/haas-nikitamazepin-02-4-1024x683.jpg\" alt=\"\" class=\"wp-image-512890\"\/><figcaption>Nikita Mazepin est\u00e1 aberto \u00e0 possibilidade de ter um piloto reserva com mais experi\u00eancia na Haas em 2022 (Foto: Haas)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conhe\u00e7a o canal do Grande Pr\u00eamio no YouTube! Clique&nbsp;<a target=\"_blank\" href=\"https:\/\/youtube.com\/GrandePremioTV\" rel=\"noreferrer noopener\">aqui<\/a>.<br>Siga o Grande Pr\u00eamio no&nbsp;<a target=\"_blank\" href=\"https:\/\/twitter.com\/grandepremio\" rel=\"noreferrer noopener\">Twitter&nbsp;<\/a>e no&nbsp;<a target=\"_blank\" href=\"https:\/\/instagram.com\/grandepremio\" rel=\"noreferrer noopener\">Instagram<\/a>!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro das pistas, Schumacher e Mazepin <a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/briga-entre-mick-schumacher-nikita-mazepin-ganha-ares-incontornavel-tumultua-futuro-haas\/\" target=\"_blank\" rel=\"noreferrer noopener\">tamb\u00e9m costumam discordar<\/a>. Em algumas ocasi\u00f5es nesta temporada, como nos GPs da Holanda e da It\u00e1lia, os dois pilotos se estranharam com <a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/nikita-mazepin-lamenta-acidente-mick-schumacher-monza-e-assume-culpa-minha\/\" target=\"_blank\" rel=\"noreferrer noopener\">toques na pista e algumas explos\u00f5es pelo r\u00e1dio<\/a>. O russo, ali\u00e1s, costuma gerar rea\u00e7\u00f5es no paddock por suas a\u00e7\u00f5es, no m\u00ednimo, controversas na pista, <a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/chefe-haas-culpar-nikita-mazepin-prensar-mick-schumacher-diz-nao-vamos-aceitar\/\" target=\"_blank\" rel=\"noreferrer noopener\">e j\u00e1 levou um pux\u00e3o de orelha da pr\u00f3pria equipe<\/a> por prensar o companheiro durante a corrida de Zandvoort.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Haas \u00e9 a \u00faltima colocada na tabela do Mundial de Construtores, sem conseguir somar pontos. O melhor resultado alcan\u00e7ado pela equipe foi um 12\u00ba lugar conquistado por Schumacher no GP da Hungria, quando v\u00e1rios carros abandonaram ap\u00f3s acidente protagonizado por Valtteri Bottas, da Mercedes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A disputa da F\u00f3rmula 1 retorna no pr\u00f3ximo fim de semana, com o GP da Turquia, entre os dias 8 e 10 de outubro.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Paddockast #123: A McLaren j\u00e1 est\u00e1 na &amp;apos;F1 A&amp;apos;? O que falta?\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/12SHDwKZSt6jrlrgm9uYa6?utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Guenther Steiner cogita a contrata\u00e7\u00e3o de um reserva mais experiente na Haas, mas Mick Schumacher cr\u00ea estar &#8220;extraindo o melhor poss\u00edvel&#8221;<\/p>\n","protected":false},"author":0,"featured_media":1000512888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[2],"tags":[147,156,180,24837,1388,24898,15288,1256,119,15287,82,1294,1737,116,1389],"42wp_author":[47142],"class_list":["post-117275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f1","tag-f1","tag-f1-2021","tag-formula-1","tag-formula-1-2","tag-gp-da-holanda","tag-gp-da-italia","tag-gp-da-turquia","tag-gunther-steiner","tag-haas","tag-istambul","tag-mercedes","tag-mick-schumacher","tag-monza","tag-nikita-mazepin","tag-zandvoort","42wp_author-jp-nascimento"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/117275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=117275"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/117275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000512888"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=117275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=117275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=117275"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=117275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}