{"id":118929,"date":"2021-08-02T10:35:02","date_gmt":"2021-08-02T13:35:02","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/vice-lider-formula-e-robin-frijns-renova-contrato-com-virgin-para-2021-22\/"},"modified":"2021-08-02T10:35:10","modified_gmt":"2021-08-02T13:35:10","slug":"vice-lider-formula-e-robin-frijns-renova-contrato-com-virgin-para-2021-22","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/formula-e\/vice-lider-formula-e-robin-frijns-renova-contrato-com-virgin-para-2021-22\/","title":{"rendered":"Vice-l\u00edder da F\u00f3rmula E, Frijns renova contrato com Virgin para 2021\/22"},"content":{"rendered":"\n<figure class=\"wp-block-video\"><video class=\"video-js vjs-big-play-centered\" data-gp-vjs=\"1\" controls src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/l-videos\/Hungria_Domingo_Punido.mp4\"><\/video><figcaption>Os melhores momentos do GP da Hungria (V\u00eddeo: GRANDE PR\u00caMIO com Reuters)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O momento \u00e9 de estabilidade para Robin Frijns na F\u00f3rmula E. A Virgin anunciou na manh\u00e3 desta segunda-feira (2) a decis\u00e3o de renovar o contrato do holand\u00eas por mais um ano, at\u00e9 o fim da temporada 2021\/22.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frijns conseguiu convencer a Virgin atrav\u00e9s de uma temporada regular na F\u00f3rmula E. Mesmo sem vencer, o piloto deu um salto na compara\u00e7\u00e3o com o ano anterior e ganhou for\u00e7a na briga pelo t\u00edtulo de 2020\/21. Robin \u00e9 o vice-l\u00edder, <strong><a href=\"https:\/\/www.grandepremio.com\/br\/formula-e\/noticias\/nyck-de-vries-vira-lider-piloto-a-ser-batido-decisao-formula-e-confira-classificacao\/\">6 pontos atr\u00e1s do compatriota Nyck de Vries<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFico muito feliz por continuar na Virgin por mais uma temporada\u201d, disse Frijns. \u201cTemos um grande carro e uma equipe muito talentosa, que faz um trabalho fenomenal. Juntos, n\u00f3s mostramos consist\u00eancia no campeonato mais imprevis\u00edvel do mundo. N\u00e3o \u00e9 f\u00e1cil, o que ajuda a explicar como estamos na parte de cima da tabela\u201d, seguiu.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2021\/05\/ROBIN-FRINJS-1024x683.jpg\" alt=\"\" class=\"wp-image-471714\"\/><figcaption>Robin Frijns (Foto: F\u00f3rmula E)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTer o Nick [Cassidy] na equipe \u00e9 \u00f3timo tamb\u00e9m. Trabalhamos juntos e nos completamos. O n\u00edvel de talento no grid da F\u00f3rmula E \u00e9 incrivelmente alto, e esse campeonato fica mais dif\u00edcil a cada ano. Voc\u00ea precisa da melhor equipe ao seu redor para ter sucesso. Sinto que, como um todo, estamos em uma boa posi\u00e7\u00e3o para as \u00faltimas corridas do ano e para a oitava temporada\u201d, destacou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O novo contrato de apenas um ano diz muito sobre uma Virgin que ainda tem futuro incerto. A equipe segue com trem de for\u00e7a da Audi em 2021\/22, mas vai precisar de uma nova parceira para 2022\/23: a marca alem\u00e3 se despede por completo da F\u00f3rmula E e vira aus\u00eancia no primeiro campeonato com carros Gen 3. Caber\u00e1 \u00e0 equipe brit\u00e2nica a decis\u00e3o de seguir ou n\u00e3o no grid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cassidy, elogiado por Frijns, ainda tem futuro incerto. Dito isso, o neozeland\u00eas faz bom trabalho: estreante, j\u00e1 conseguiu duas poles e dois p\u00f3dios, surgindo em s\u00e9timo no Campeonato de Pilotos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A F\u00f3rmula E encerra a temporada dentro de duas semanas. A categoria vai para Berlim, onde realiza ePs nos dias 14 e 15 de agosto.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-dailymotion wp-block-embed-dailymotion wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"NOVO FORMATO DE CLASSIFICA\u00c7\u00c3O NA F\u00d3RMULA E? J\u00c1 PASSOU DA HORA | GP \u00e0s 10\" frameborder=\"0\" width=\"500\" height=\"281\" src=\"https:\/\/geo.dailymotion.com\/player.html?video=x82ukn2&#038;\" allowfullscreen allow=\"autoplay; fullscreen; picture-in-picture; web-share\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conhe\u00e7a o canal do Grande Pr\u00eamio no YouTube! Clique\u00a0<a target=\"_blank\" href=\"https:\/\/youtube.com\/GrandePremioTV\" rel=\"noreferrer noopener\">aqui<\/a>.<br>Siga o Grande Pr\u00eamio no\u00a0<a target=\"_blank\" href=\"https:\/\/twitter.com\/grandepremio\" rel=\"noreferrer noopener\">Twitter\u00a0<\/a>e no\u00a0<a target=\"_blank\" href=\"https:\/\/instagram.com\/grandepremio\" rel=\"noreferrer noopener\">Instagram<\/a>!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Robin Frijns, em busca de um t\u00edtulo in\u00e9dito na F\u00f3rmula E, segue na Virgin por mais um ano. Nick Cassidy, companheiro de equipe, segue com futuro incerto no certame el\u00e9trico<\/p>\n","protected":false},"author":0,"featured_media":1000452273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[19],"tags":[26482,25000,28327,2128,1593,639],"42wp_author":[47118],"class_list":["post-118929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formula-e","tag-fe-2021","tag-formula-e-2","tag-formula-e-2022","tag-nick-cassidy","tag-robin-frijns","tag-virgin","42wp_author-vitor-fazio"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/118929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=118929"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/118929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000452273"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=118929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=118929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=118929"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=118929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}