{"id":130722,"date":"2020-04-20T08:18:00","date_gmt":"2020-04-20T11:18:00","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/aberto-a-tudo-e-qualquer-coisa-silverstone-tambem-aceita-gp-sem-publico\/"},"modified":"2020-05-23T09:18:40","modified_gmt":"2020-05-23T12:18:40","slug":"aberto-a-tudo-e-qualquer-coisa-silverstone-tambem-aceita-gp-sem-publico","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/f1\/aberto-a-tudo-e-qualquer-coisa-silverstone-tambem-aceita-gp-sem-publico\/","title":{"rendered":"Aberto \u201ca tudo e qualquer coisa\u201d, Silverstone tamb\u00e9m aceita GP sem p\u00fablico"},"content":{"rendered":"\n<div>\n\tO GP da Inglaterra tem potencial para virar mais um sem p&uacute;blico no calend&aacute;rio da <strong><a href=\"https:\/\/grandepremio.com\/br\/f1\"><span style=\"color:#ff0000\">F&oacute;rmula 1<\/span><\/a><\/strong>. A administra&ccedil;&atilde;o de Silverstone, aut&oacute;dromo j&aacute; cotado para <strong><a href=\"https:\/\/grandepremio.com\/br\/f1\/noticias\/inicio-na-austria-e-rodada-tripla-em-silverstone-como-f1-planeja-abrir-temporada\"><span style=\"color:#ff0000\">receber mais de um GP no calend&aacute;rio modificado de 2020<\/span><\/a><\/strong>, agora tamb&eacute;m diz aceitar de realizar eventos com port&otilde;es fechados, possibilidade cada vez mais real em dias de pandemia do coronav&iacute;rus.<\/div>\n<div>\n\t&nbsp;<\/div>\n<div>\n\t&ldquo;A F1 est&aacute; trabalhando muito pesado para descobrir a solu&ccedil;&atilde;o para o campeonato&rdquo;, disse Stuart Pringle, diretor administrativo de Silverstone, em entrevista ao jornal brit&acirc;nico &lsquo;The Guardian&rsquo;. &ldquo;N&oacute;s estamos em contato frequente com eles e j&aacute; nos perguntaram se poder&iacute;amos receber uma corrida ou duas, se poderia ser com port&otilde;es fechados. A resposta &eacute; sim, certamente. Estamos abertos para pensar em tudo e qualquer coisa. Acho que a F1 vai tomar uma decis&atilde;o a respeito do calend&aacute;rio no come&ccedil;o de maio. Eles n&atilde;o podem dar a partida na temporada a menos que tenham uma solu&ccedil;&atilde;o com chances de dar certo. Esse prazo [defini&ccedil;&atilde;o em maio] funciona para n&oacute;s se n&atilde;o tivermos de montar infraestrutura para o p&uacute;blico&rdquo;, seguiu.<\/div>\n<div>\n<div class=\"imagem-noticia\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2020\/04\/2019819102432_MI2_II.jpg\" title=\"Silverstone (Foto: Michelin)\" \/><\/div>\n<div class=\"legenda-imagem\">\n\t\t#iconeimagem Silverstone n&atilde;o tem problemas com GPs de port&otilde;es fechados (Foto: Michelin)<\/div>\n<\/div>\n<div>\n\tSilverstone parece ser a grande esperan&ccedil;a da F1 de inchar o calend&aacute;rio 2020, que j&aacute; tem duas provas canceladas, Austr&aacute;lia e M&ocirc;naco, e sete adiadas. Uma alternativa revelada pelo site &lsquo;Race Fans&rsquo; &eacute; a realiza&ccedil;&atilde;o de tr&ecirc;s provas na pista brit&acirc;nica, fazendo uso de diferentes configura&ccedil;&otilde;es do tra&ccedil;ado. A op&ccedil;&atilde;o mais realista ainda &eacute; de duas corridas, mas sem formato definido at&eacute; aqui.<\/div>\n<div>\n\t&nbsp;<\/div>\n<div>\n\t&ldquo;N&oacute;s j&aacute; conversamos sobre todas op&ccedil;&otilde;es, incluindo duas corridas em um fim de semana e duas corridas em fins de semana seguidos. Eu tenho confian&ccedil;a completa na nossa habilidade de lidar com esses eventos. Temos muita experi&ecirc;ncia, muito conhecimento e definitivamente podemos encarar&rdquo;, destacou Pringle.<\/div>\n<div>\n\t&nbsp;<\/div>\n<div>\n\tAl&eacute;m de Silverstone, o Red Bull Ring tamb&eacute;m flerta com os port&otilde;es fechados. A F&oacute;rmula 1 luta para chegar ao m&iacute;nimo de 15 GPs, que ainda honra contratos televisivos e evita renegocia&ccedil;&otilde;es. Para isso, &eacute; poss&iacute;vel que a temporada se arraste at&eacute; janeiro.<\/div>\n<div>\n\t&nbsp;<\/div>\n<div class=\"embed-responsive embed-responsive-16by9\">\n\t<\/div>\n<p><\/p>\n<table bgcolor=\"#add8e6<\/p>\n<p>&#8221; border=&#8221;1&#8243; cellpadding=&#8221;1&#8243; cellspacing=&#8221;1&#8243; style=&#8221;width: 100%&#8221;><\/p>\n<tbody>\n<tr>\n<td>\n\t\t\t\t<span style=\"color:#000000\"><span style=\"font-size:18px\"><strong>Paddockast #57<br \/>\n\t\t\t\tMARIANA BECKER e os bastidores da F1<\/strong><\/span><\/span><br \/>\n\t\t\t\t<br \/>\n\t\t\t\tOu&ccedil;a: <a href=\"http:\/\/open.spotify.com\/show\/5OBbp8MzxQymoyneX4IviF?si=gYqPr53GSaa-AcxFpOzJHg\">Spotify<\/a> | <a href=\"http:\/\/podcasts.apple.com\/br\/podcast\/paddockast\/id1371540198\">iTunes<\/a> | <a href=\"http:\/\/www.subscribeonandroid.com\/www.central3.com.br\/category\/podcasts\/paddockast\/feed\/podcast\/\">Android<\/a> | <a href=\"http:\/\/player.fm\/series\/paddockast\">playerFM<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<table bgcolor=\"#98FB98\" border=\"0\" cellpadding=\"1\" cellspacing=\"1\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td>\n<div>\n\t\t\t\t\t<span style=\"color:#000000\"><span style=\"font-size:18px\"><strong>COMO SE PREVENIR DO CORONAV&Iacute;RUS:<\/strong><\/span><\/span><br \/>\n\t\t\t\t\t&nbsp;<\/div>\n<p>\t\t\t\t<strong><span style=\"font-size:18px\">\u261e&nbsp;Lave as m&atilde;os com &aacute;gua e sab&atilde;o ou use &aacute;lcool em gel.<br \/>\n\t\t\t\t\u261e&nbsp;Cubra o nariz e boca ao espirrar ou tossir.<br \/>\n\t\t\t\t\u261e&nbsp;Evite aglomera&ccedil;&otilde;es.<br \/>\n\t\t\t\t\u261e&nbsp;Mantenha os ambientes bem ventilados.<br \/>\n\t\t\t\t\u261e&nbsp;N&atilde;o compartilhe objetos pessoais.<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<div>\n<div>\n<table bgcolor=\"#E6E6E6\" border=\"0\" cellpadding=\"1\" cellspacing=\"1\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td>\n<div>\n\t\t\t\t\t\t\t<b><span style=\"color:#FF0040\">Apoie o <strong> GRANDE PR&Ecirc;MIO<\/strong><\/span><\/b><span style=\"color:#FF0040\">: garanta o futuro do nosso jornalismo <\/span><br \/>\n\t\t\t\t\t\t\t<br \/>\n\t\t\t\t\t\t\tO<strong> GRANDE PR&Ecirc;MIO <\/strong>&eacute; a maior m&iacute;dia digital de esporte a motor do Brasil, na Am&eacute;rica Latina e em L&iacute;ngua Portuguesa, editorialmente independente. Nossa grande equipe produz conte&uacute;do di&aacute;rio e pensa em inova&ccedil;&otilde;es constantemente, e n&atilde;o s&oacute; na internet: uma das nossas atua&ccedil;&otilde;es est&aacute; na realiza&ccedil;&atilde;o de eventos, como a Copa GP de Kart. Assim, seu apoio &eacute; sempre importante.<br \/>\n\t\t\t\t\t\t\t<br \/>\n\t\t\t\t\t\t\t<a href=\"https:\/\/grandepremium.grandepremio.com\/br\/assine\" target=\"_blank\" rel=\"noopener noreferrer\">Assine o GRANDE PREMIUM<\/a>: veja os planos e o que oferecem, tenha &agrave; disposi&ccedil;&atilde;o uma s&eacute;rie de benef&iacute;cios e experi&ecirc;ncias exclusivas, e fa&ccedil;a parte de um grupo especial, a Scuderia GP, com debate em alto n&iacute;vel.<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al&eacute;m da op&ccedil;&atilde;o de receber mais de um GP de F1 na mesma temporada, Silverstone tamb&eacute;m diz aceitar corridas sem p&uacute;blico. O diretor do aut&oacute;dromo Stuart Pringle mant&eacute;m contato com a categoria e aguarda calend&aacute;rio redefinido em maio<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[2],"tags":[118,24837,1505,3632],"42wp_author":[47109],"class_list":["post-130722","post","type-post","status-publish","format-standard","hentry","category-f1","tag-f1-2020","tag-formula-1-2","tag-gp-da-inglaterra","tag-silverstone","42wp_author-redacao-gp"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/130722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=130722"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/130722\/revisions"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=130722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=130722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=130722"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=130722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}