{"id":135517,"date":"2019-06-23T07:58:00","date_gmt":"2019-06-23T10:58:00","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/domingo-de-gp-da-franca-traz-temperaturas-mais-altas-e-ceu-ensolarado-em-paul-ricard\/"},"modified":"2020-05-17T05:43:13","modified_gmt":"2020-05-17T08:43:13","slug":"domingo-de-gp-da-franca-traz-temperaturas-mais-altas-e-ceu-ensolarado-em-paul-ricard","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/f1\/domingo-de-gp-da-franca-traz-temperaturas-mais-altas-e-ceu-ensolarado-em-paul-ricard\/","title":{"rendered":"Domingo de GP da Fran\u00e7a traz temperaturas mais altas e c\u00e9u ensolarado em Paul Ricard"},"content":{"rendered":"\n<div>\n\tS&atilde;o Pedro separou um clima especial para o domingo (23) em Paul Ricard, casa da <a href=\"https:\/\/grandepremio.com\/br\/f1\">F&oacute;rmula 1<\/a> neste fim de semana. O c&eacute;u segue ensolarado no sul da Fran&ccedil;a, com poucas nuvens no c&eacute;u. Isso significa um GP da Fran&ccedil;a com calor e pista seca.<\/div>\n<div>\n\t&nbsp;<\/div>\n<div>\n\t&Eacute; poss&iacute;vel dizer que o clima ficou com ainda mais cara de ver&atilde;o em Paul Ricard. As temperaturas subiram desde o s&aacute;bado, passando da casa de 26&ordm; C para 29&ordm; C, de acordo com informa&ccedil;&otilde;es do Weather Channel. De quebra, o clima est&aacute; mais seco, com a umidade relativa do ar passando da casa de 50% para girar entre 39% e 43% ao longo da tarde.<\/div>\n<div>\n<div class=\"imagem-noticia\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2019\/06\/2019622855898_Renault_NicoHulkenberg_32_II.jpg\" title=\"Nico H\u00fclkenberg (Foto: Renault)\" \/><\/div>\n<div class=\"legenda-imagem\">\n\t\t#iconeimagem Nico H&uuml;lkenberg (Foto: Renault)<\/div>\n<div style=\"float: left;margin-right: 15px;margin-bottom:15px\">\n\t\t<\/div>\n<p>\tDesse jeito, n&atilde;o surpreende que o risco de chuva seja zero ao longo da tarde. O clima s&oacute; deve ficar mais nublado, trazendo chance pequena de intemp&eacute;rie, por volta das 23h na hora local.<\/p><\/div>\n<div>\n\t&nbsp;<\/div>\n<div>\n\t<a href=\"https:\/\/grandepremio.com\/br\/f1\/noticias\/hamilton-supera-bottas-em-briga-particular-da-mercedes-na-franca-e-carimba-pole\">O GP da Fran&ccedil;a tem Lewis Hamilton na pole-position<\/a>. O brit&acirc;nico tenta encaixar a quarta vit&oacute;ria seguida na temporada 2019, o que representaria um golpe duro em Valtteri Bottas na luta pelo t&iacute;tulo. Charles Leclerc parte da terceira posi&ccedil;&atilde;o, tentando incomodar a dupla da Mercedes de alguma forma.<\/div>\n<p><\/p>\n<div>\n<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As temperaturas em Paul Ricard seguem subindo, com o term&ocirc;metros batendo na casa dos 30&ordm; C ao longo da tarde de domingo. Com c&eacute;u ensolarado e umidade mais baixa, n&atilde;o surpreende que a chance de chuva seja nula<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[2],"tags":[610,87,82,536,612],"42wp_author":[47109],"class_list":["post-135517","post","type-post","status-publish","format-standard","hentry","category-f1","tag-largada","tag-lewis-hamilton","tag-mercedes","tag-paul-ricard","tag-valtteri-bottas","42wp_author-redacao-gp"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/135517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=135517"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/135517\/revisions"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=135517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=135517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=135517"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=135517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}