{"id":58055,"date":"2024-10-17T18:19:20","date_gmt":"2024-10-17T21:19:20","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/fernando-alonso-minimiza-marca-400-corridas-f1-preferiria-metade-mais-titulo\/"},"modified":"2024-10-17T19:47:43","modified_gmt":"2024-10-17T22:47:43","slug":"fernando-alonso-minimiza-marca-400-corridas-f1-preferiria-metade-mais-titulo","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/f1\/fernando-alonso-minimiza-marca-400-corridas-f1-preferiria-metade-mais-titulo\/","title":{"rendered":"Alonso minimiza marca de 400 corridas na F1: &#8220;Preferiria metade e mais um t\u00edtulo&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bicampe\u00e3o mundial, o espanhol <strong>Fernando Alonso <\/strong>est\u00e1 perto de um n\u00famero hist\u00f3rico na <strong>F\u00f3rmula 1<\/strong>. No <strong>GP da Cidade do M\u00e9xico<\/strong>, marcado para o pr\u00f3ximo fim de semana, o piloto da <strong>Aston Martin <\/strong>se tornar\u00e1 o primeiro na hist\u00f3ria da categoria a chegar ao n\u00famero de 400 GPs disputados. Por\u00e9m, o veterano de 43 anos est\u00e1 pouco impressionado com o feito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em entrevista a jornalistas espanh\u00f3is antes do GP dos Estados Unidos, Fernando apontou que gostaria de ter mais um t\u00edtulo ou mais vit\u00f3rias em vez de 400 corridas. Alonso quebrou o recorde de pilotos com mais provas na <strong>F\u00f3rmula 1 <\/strong>ao superar o finland\u00eas <strong>Kimi R\u00e4ikk\u00f6nen <\/strong>no <strong>GP da It\u00e1lia de 2022.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Est\u00e1 tudo bem, estou consciente do n\u00famero. Mas s\u00e3o estat\u00edsticas que n\u00e3o me interessam. Gostaria de ter corrido metade destas provas e ter um t\u00edtulo a mais, ou mais vit\u00f3rias. Essas s\u00e3o as estat\u00edsticas importantes. Demonstra meu amor pelo esporte e a disciplina por render em um alto n\u00edvel por mais de 30 anos. Espero celebrar no M\u00e9xico em um bom fim de semana. N\u00e3o estou pensando nas pr\u00f3ximas 400, por que isso n\u00e3o vai acontecer. Mas ao menos 40 ou 50 nos pr\u00f3ximos anos&#8221;, declarou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;Inscreva-se nos dois canais do GRANDE PR\u00caMIO no YouTube:&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9OlHEgxoaY6QY6nWPoiqQg?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP<\/a>&nbsp;|&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9csiS6q_C3C0FYhyr1rnFA?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP2<\/a><\/strong><br><strong>&nbsp;LEIA TAMB\u00c9M:&nbsp;<a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/lando-norris-perde-prazo-transformar-dominio-titulo-so-bate-max-verstappen-sorte\/\">Norris perde prazo de transformar dom\u00ednio em t\u00edtulo e s\u00f3 bate Verstappen com sorte<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2024\/09\/singapura-2024-f1-corrida-aston-martin-fernando-alonso-afp-01-1200x800.jpg\" alt=\"\" class=\"wp-image-872274\"\/><figcaption class=\"wp-element-caption\">Fernando Alonso comentou sobre a for\u00e7a da Ferrari em Singapura (Foto: AFP)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Depois de pontos seguidos nos GPs do Azerbaij\u00e3o e de Singapura, Alonso n\u00e3o demonstra muito otimismo, nem com as atualiza\u00e7\u00f5es da AMR24. Nas m\u00e3os do espanhol, o carro saiu de uma sequ\u00eancia ruim entre as etapas da Em\u00edlia-Romanha e da \u00c1ustria, voltando a marcar pontos com frequ\u00eancia, apesar de n\u00e3o romper a barreira do top-5.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;As expectativas n\u00e3o s\u00e3o t\u00e3o altas. Temos pe\u00e7as novas, mas creio que n\u00e3o v\u00e3o mudar a situa\u00e7\u00e3o do carro. Todas as evolu\u00e7\u00f5es agora s\u00e3o pequenas e est\u00e3o direcionadas para o carro de 2025 no t\u00fanel de vento. Uma metade \u00e9 teste, a outra \u00e9 desempenho. Para n\u00f3s, \u00e9 importante, temos que manter a forma e entender o carro que temos desde a Hungria. Neste fim de semana precisamos de uma boa correla\u00e7\u00e3o, que todas as pe\u00e7as fa\u00e7am o que esperamos delas, mas em termos de desempenho ou posi\u00e7\u00f5es de classifica\u00e7\u00e3o e corrida, n\u00e3o espero que haja grandes mudan\u00e7as&#8221;, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Desde Budapeste, entendemos algumas dire\u00e7\u00f5es que tomamos no passado e porqu\u00ea a correla\u00e7\u00e3o n\u00e3o era adequada na pista. Este pacote fez o que esper\u00e1vamos e isso \u00e9 uma continua\u00e7\u00e3o, estamos otimistas e esperamos ver o que queremos ver, embora agora todas as equipes tragam atualiza\u00e7\u00f5es. 0s1, 0s05 e ficamos todos nas mesmas posi\u00e7\u00f5es. Acho que vai acontecer assim&#8221;, concluiu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O&nbsp;<strong>GRANDE PR\u00caMIO<\/strong>&nbsp;acompanha&nbsp;<a href=\"https:\/\/www.grandepremio.com\/br\/ao-vivo\/f1\/\"><strong>AO VIVO e EM&nbsp;<\/strong><\/a><a href=\"https:\/\/www.grandepremio.com\/br\/ao-vivo\/\"><\/a><strong><a href=\"https:\/\/www.grandepremio.com\/br\/ao-vivo\/\" target=\"_blank\" rel=\"noreferrer noopener\">TEMPO REAL<\/a><\/strong>&nbsp;todas as atividades do&nbsp;<strong>GP dos Estados Unidos, em Austin<\/strong>&nbsp;e transmite sprint shootout, classifica\u00e7\u00e3o e corridas em segunda tela, em parceria com a Voz do Esporte, na&nbsp;<a href=\"https:\/\/www.youtube.com\/c\/GrandePremioTV\/streams\"><strong>GPTV, o canal do GP no Youtube<\/strong><\/a>. Depois das atividades de cada dia, debate tudo o que aconteceu no Briefing. Na sexta-feira (18), o&nbsp;<strong>treino livre<\/strong>&nbsp;est\u00e1 marcado para a 14h30 (de Bras\u00edlia GMT-3). Depois, \u00e0s 18h30, acontece a&nbsp;<strong>classifica\u00e7\u00e3o da sprint<\/strong>. No s\u00e1bado (19), a&nbsp;<strong>prova curta&nbsp;<\/strong>ser\u00e1 \u00e0s 15h, com a&nbsp;<strong>classifica\u00e7\u00e3o<\/strong>&nbsp;\u00e0s 19h. No&nbsp;domingo (20)<strong>, a largada<\/strong>&nbsp;est\u00e1 marcada para as 16h.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"F1 de VOLTA na GLOBO em 2025 (COM N\u00c3O AN\u00daNCIO) e PR\u00c9VIA do GP dos EUA | WGP\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/eD5dWasIfpw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Fernando Alonso minimizou a marca de 400 corridas na F\u00f3rmula 1, que alcan\u00e7ar\u00e1 no pr\u00f3ximo fim de semana, no M\u00e9xico. Bicampe\u00e3o admitiu que trocaria metade delas por ter mais um t\u00edtulo <\/p>\n","protected":false},"author":0,"featured_media":1000871381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[2],"tags":[309,1982,12757,5660,32996,969,5921,2614,147,3230,642,160,176,180,30909,24977,2318,1491,30103,28285,2306,510,836,34066,3132,35345,2610,2052,2048,2036,33981],"42wp_author":[47119],"class_list":["post-58055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f1","tag-aston-martin","tag-austin","tag-circuito-das-americas","tag-classificacao","tag-classificacao-sprint","tag-corrida","tag-corrida-sprint","tag-cota","tag-f1","tag-f1-2024","tag-f1-ao-vivo","tag-f1-tv","tag-fernando-alonso","tag-formula-1","tag-formula-1-2024","tag-gp-dos-estados-unidos","tag-gp-dos-eua","tag-grande-premio","tag-grande-premio-f1","tag-grandepremio","tag-grid-de-largada","tag-pole","tag-recorde","tag-segunda-tela","tag-sergio-perez","tag-temporada-2024","tag-texas","tag-treino-livre-1","tag-treino-livre-2","tag-treinos-livres","tag-voz-do-esporte","42wp_author-gabriel-carvalho"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/58055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=58055"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/58055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000871381"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=58055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=58055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=58055"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=58055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}