{"id":89321,"date":"2024-01-27T17:23:01","date_gmt":"2024-01-27T20:23:01","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/robin-frijns-elogia-disputa-nick-cassidy-2o-diriyah-quase-nos-matamos\/"},"modified":"2024-01-27T17:25:32","modified_gmt":"2024-01-27T20:25:32","slug":"robin-frijns-elogia-disputa-nick-cassidy-2o-diriyah-quase-nos-matamos","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/formula-e\/robin-frijns-elogia-disputa-nick-cassidy-2o-diriyah-quase-nos-matamos\/","title":{"rendered":"Frijns elogia disputa com Cassidy ap\u00f3s 2\u00ba em Diriyah: &#8220;Quase nos matamos&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De volta \u00e0 <strong>Envision<\/strong> ap\u00f3s uma temporada com a <strong>Abt-Cupra<\/strong>, <strong>Robin Frijns<\/strong> conquistou seu primeiro p\u00f3dio na temporada de 2024 da <strong>F\u00f3rmula E<\/strong> neste s\u00e1bado (27). Largando em segundo, o holand\u00eas assumiu a lideran\u00e7a ainda na primeira curva, <a href=\"https:\/\/www.grandepremio.com\/br\/formula-e\/noticias\/oliver-rowland-se-diz-aliviado-pole-diriyah-dois-anos-dificeis-formula-e\/\" class=\"ek-link\">ultrapassando o pole <strong>Oliver Rowland<\/strong><\/a>, mas acabou sendo superado por <strong>Nick Cassidy<\/strong>, que fez uma estrat\u00e9gia diferente com o modo ataque <a href=\"https:\/\/www.grandepremio.com\/br\/formula-e\/noticias\/nick-cassidy-controla-robin-frijns-fecha-fim-semana-cerebral-vitoria-ep-diriyah-2\/\" class=\"ek-link\">para assumir a ponta e garantir a vit\u00f3ria<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O segundo lugar deu \u00e0 Frijns seu primeiro p\u00f3dio desde o eP de Nova Iorque 1 de 2022. Agora no carro que Cassidy levou ao vice-campeonato na \u00faltima temporada, o holand\u00eas elogiou a disputa com o rival e destacou que os dois se levaram a limite no <strong>eP de Diriyah 2<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u00c9, o come\u00e7o foi muito bom. Eu tinha um bom ritmo e estava liderando, estava feliz e confort\u00e1vel&#8221;, contou Robin. &#8220;Mas a\u00ed comecei a disputar com o Nick, come\u00e7amos a abrir dist\u00e2ncia para os outros e est\u00e1vamos quase nos matando, mas ele fez um grande trabalho. Eu garanti a segunda posi\u00e7\u00e3o, bons pontos e espero que na pr\u00f3xima corrida possa terminar um lugar acima&#8221;, comemorou Frijns.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f\u00a0Inscreva-se nos dois canais do GRANDE PR\u00caMIO no YouTube:\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC9OlHEgxoaY6QY6nWPoiqQg?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC9csiS6q_C3C0FYhyr1rnFA?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP2<\/a><\/strong><br><strong>\u25b6\ufe0f\u00a0<a href=\"https:\/\/www.twitch.tv\/grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a o canal do GRANDE PR\u00caMIO na Twitch clicando aqui!<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2024\/01\/frijns-robin-1024x683.jpeg\" alt=\"\" class=\"wp-image-772742\"\/><figcaption class=\"wp-element-caption\">Robin Frijns voltou ao p\u00f3dio com a Envision (Foto: Envision)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O come\u00e7o de 2024 n\u00e3o foi bom para o veterano de 32 anos. Em sua oitava temporada na <strong>F\u00f3rmula E,<\/strong> ele <a href=\"https:\/\/www.grandepremio.com\/br\/video\/formula-e\/robin-frijns-escorrega-bate-muro-causa-safety-car-ep-cidade-do-mexico\/\" class=\"ek-link\">havia batido no <strong>eP da Cidade do M\u00e9xico<\/strong> <\/a>e conquistado apenas um ponto na primeira corrida na Ar\u00e1bia Saudita. Questionado se o p\u00f3dio poderia ser um divisor de \u00e1guas, Frijns disse que est\u00e1 cada vez mais adaptado ao carro e destacou que ainda h\u00e1 espa\u00e7o para melhora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Tivemos dificuldades no come\u00e7o da temporada. Mas comecei a me adaptar mais, obviamente o Nick que havia pilotado durante o \u00faltimo ano. Ainda h\u00e1 mais alguns passos a serem dados, mas eu aceito esse resultado!&#8221;, concluiu Robin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00a0<a href=\"https:\/\/www.grandepremio.com\/br\/formula-e\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.grandepremio.com\/br\/formula-e\/\" target=\"_blank\" rel=\"noreferrer noopener\">F\u00f3rmula E<\/a>\u00a0retorna agora entre os dias 15 e 16 de mar\u00e7o, com o\u00a0<strong>eP de\u00a0<a href=\"https:\/\/www.grandepremio.com\/br\/circuito\/sao-paulo\/\" target=\"_blank\" rel=\"noreferrer noopener\">S\u00e3o Paulo<\/a><\/strong>, que ter\u00e1 cobertura \u2018<strong>in loco<\/strong>\u2018 do\u00a0<strong>GRANDE PR\u00caMIO<\/strong>. O\u00a0<strong>GP<\/strong>\u00a0\u00e9 emissora oficial da\u00a0<strong><a href=\"https:\/\/www.grandepremio.com\/br\/formula-e\/\" target=\"_blank\" rel=\"noreferrer noopener\">F\u00f3rmula E<\/a><\/strong>\u00a0no Brasil e transmite todas as atividades de pista\u00a0<strong>AO VIVO e COM IMAGENS<\/strong>\u00a0no\u00a0<strong><a href=\"https:\/\/www.youtube.com\/c\/GrandePremioTV\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">YouTube<\/a><\/strong>\u00a0e no\u00a0<strong><a href=\"https:\/\/m.kwai.com\/user\/@grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Kwai<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/bit.ly\/epSP2024GP\" target=\"_blank\" rel=\"noreferrer noopener\">Compre aqui os ingressos do eP de S\u00e3o Paulo 2024 da&nbsp;<\/a><a href=\"https:\/\/www.grandepremio.com\/br\/formula-e\/\" target=\"_blank\" rel=\"noreferrer noopener\">F\u00f3rmula E<\/a>&nbsp;com o cupom GRANDEPREMIO10<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-assista-ao-ep-de-diriyah-2\">Assista ao eP de Diriyah 2:<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"F\u00d3RMULA E 2024 - eP de Diriyah | 3\u00aa etapa | Corrida 2\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/k5ammaOFxbg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Robin Frijns conquistou seu primeiro p\u00f3dio na temporada no eP de Diriyah 2 e ressaltou que ainda h\u00e1 bastante o que melhorar para se readaptar com o carro da Envision<\/p>\n","protected":false},"author":0,"featured_media":1000772741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[19],"tags":[5660,10437,27296,27360,35967,34647,38049,38050,37545,33841,37745,910,2128,36219,1593],"42wp_author":[47144],"class_list":["post-89321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formula-e","tag-classificacao","tag-envision","tag-ep-da-arabia-saudita","tag-ep-de-diriyah","tag-formula-e-2024","tag-formula-e-ao-vivo","tag-formula-e-arabia-saudita","tag-formula-e-diriyah","tag-formula-e-live","tag-formula-e-no-grande-premio","tag-formula-e-tv-2024","tag-jaguar","tag-nick-cassidy","tag-onde-assistir-formula-e","tag-robin-frijns","42wp_author-andre-netto"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/89321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=89321"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/89321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000772741"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=89321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=89321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=89321"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=89321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}