{"id":98490,"date":"2023-10-08T17:19:59","date_gmt":"2023-10-08T20:19:59","guid":{"rendered":"https:\/\/grandepremio.com\/br\/noticias\/logan-sargeant-vai-centro-medico-desidratacao-catar-esteban-ocon-vomita-carro\/"},"modified":"2023-10-08T17:26:25","modified_gmt":"2023-10-08T20:26:25","slug":"logan-sargeant-vai-centro-medico-desidratacao-catar-esteban-ocon-vomita-carro","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/br\/f1\/logan-sargeant-vai-centro-medico-desidratacao-catar-esteban-ocon-vomita-carro\/","title":{"rendered":"Sargeant vai ao centro m\u00e9dico por desidrata\u00e7\u00e3o no Catar. Ocon vomita no carro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Com o intenso calor durante o <a href=\"https:\/\/www.grandepremio.com\/br\/f1\/noticias\/max-verstappen-passa-ileso-bagunca-pneus-vence-gp-catar-mclaren-completa-podio\/\" class=\"ek-link\"><strong>GP do Catar<\/strong>, realizado neste domingo (8)<\/a>, v\u00e1rios pilotos do grid da <strong>F\u00f3rmula 1<\/strong> acabaram passando mal durante e ap\u00f3s a corrida. <strong>Logan Sargeant<\/strong>, <strong>Esteban Ocon<\/strong>, <strong>Alexander Albon<\/strong> e <strong>Lance Stroll<\/strong> foram alguns dos que foram amparados ou por m\u00e9dicos, ou por integrantes de suas equipes por n\u00e3o estarem se sentindo bem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda durante a corrida em <strong>Lusail<\/strong>, Sargeant teve de abandonar a prova na volta 40 por desidrata\u00e7\u00e3o e foi levado ao centro m\u00e9dico do aut\u00f3dromo para observa\u00e7\u00e3o. <\/p>\n\n\n\n<figure class=\"wp-block-video\"><video class=\"video-js vjs-big-play-centered\" data-gp-vjs=\"1\" controls src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2023\/10\/Stroll.mp4\"><\/video><figcaption class=\"wp-element-caption\">Stroll passa mal e vai direto para ambul\u00e2ncia <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Logan est\u00e1 se sentindo muito mal. Ele reclamou que estava prestes a vomitar em seu capacete, e com essas circunst\u00e2ncias, em uma das pistas mais dif\u00edceis do ano, \u00e9 nossa responsabilidade cuidar de sua sa\u00fade&#8221;, afirmou <strong>James Vowles<\/strong>, chefe de equipe da <strong>Williams<\/strong>, ap\u00f3s o americano deixar a corrida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6\ufe0f&nbsp;Inscreva-se nos dois canais do GRANDE PR\u00caMIO no YouTube:&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9OlHEgxoaY6QY6nWPoiqQg?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP<\/a>&nbsp;|&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9csiS6q_C3C0FYhyr1rnFA?sub_confirmation=1\" target=\"_blank\" rel=\"noreferrer noopener\">GP2<\/a><\/strong><br><strong>\u25b6\ufe0f&nbsp;<a href=\"https:\/\/www.twitch.tv\/grandepremio\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a o canal do GRANDE PR\u00caMIO na Twitch clicando aqui!<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais tarde, a equipe de Grove emitiu um comunica\u00e7\u00e3o sobre a situa\u00e7\u00e3o de Sargeant. &#8220;Ap\u00f3s a sa\u00edda de Logan da prova, ele foi avaliado e liberado pela equipe m\u00e9dica no local ao sofrer de desidrata\u00e7\u00e3o intensa durante a corrida, enfraquecido por ter sintomas de gripe no in\u00edcio da semana.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O outro piloto da Williams, Albon, tamb\u00e9m se sentiu mal assim que a prova terminou e teve dificuldades em deixar seu carro, demorando quase 2min para assim fazer. O tailand\u00eas foi mais um avisitar o centro m\u00e9dico de Lusail por &#8220;exposi\u00e7\u00e3o aguda ao calor&#8221;, segundo o time de Grove. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stroll estava na mesma situa\u00e7\u00e3o, e ao deixar seu Aston Martin foi diretamente falar com os atendentes de uma ambul\u00e2ncia que, para sua sorte, estava parada ao lado de onde o canadense estacionou o AMR23.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video class=\"video-js vjs-big-play-centered\" data-gp-vjs=\"1\" controls src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2023\/10\/albon.mp4\"><\/video><figcaption class=\"wp-element-caption\">Albon foi outro a ter dificuldades em deixar seu carro ao final da prova<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Esteban Ocon tamb\u00e9m se sentiu mal durante o GP do Catar falando que antes da volta 15 j\u00e1 havia passado mal. &#8220;Sugiro que j\u00e1 deixe bebidas prontas assim que a corrida acabar. Est\u00e1 muito quente. N\u00e3o disse a voc\u00eas, mas eu vomitei na volta 15&#8221;, disse pelo r\u00e1dio da Alpine ao final da prova.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A&nbsp;<a href=\"https:\/\/www.grandepremio.com\/formula-1\/\" target=\"_blank\" rel=\"noreferrer noopener\">F\u00f3rmula 1<\/a>&nbsp;volta daqui a duas semanas, entre os dias 20 e 22 de outubro, em Austin, com o <strong>GP dos Estados Unidos<\/strong>, o primeiro da \u00faltima perna tripla da temporada. E o&nbsp;<strong>GRANDE PR\u00caMIO<\/strong>&nbsp;acompanha tudo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"VERSTAPPEN vence, McLAREN vai ao P\u00d3DIO da F1 2023 no Catar | Briefing\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/jccR-igX-3c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Lance Stroll e Alexander Albon tamb\u00e9m passaram mal ao final da prova em Lusail. V\u00e1rios  pilotos reclamaram do forte calor no Catar<\/p>\n","protected":false},"author":0,"featured_media":1000738621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[2],"tags":[147,6533,600,36709,30099,30091,219,1491,30103,28285],"42wp_author":[47157],"class_list":["post-98490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f1","tag-f1","tag-f1-2023","tag-gp-do-catar","tag-gp-do-catar-2023","tag-gp-do-catar-de-f1","tag-gp-do-catar-de-formula-1","tag-grande-prmio","tag-grande-premio","tag-grande-premio-f1","tag-grandepremio","42wp_author-jonas-souza"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/98490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/comments?post=98490"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/posts\/98490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media\/1000738621"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/media?parent=98490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/categories?post=98490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/tags?post=98490"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/br\/wp-json\/wp\/v2\/42wp_author?post=98490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}