{"id":23825,"date":"2022-03-23T11:40:42","date_gmt":"2022-03-23T14:40:42","guid":{"rendered":"https:\/\/grandepremio.com\/es\/2022\/03\/23\/alphatauri-fallo-ers-causa-incendio-gasly-bahrein\/"},"modified":"2022-03-23T11:40:43","modified_gmt":"2022-03-23T14:40:43","slug":"alphatauri-fallo-ers-causa-incendio-gasly-bahrein","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/es\/f1\/alphatauri-fallo-ers-causa-incendio-gasly-bahrein\/","title":{"rendered":"AlphaTauri apunta fallo del ERS como causa del incendio en el coche de Gasly en Bahrein"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El coche de Pierre Gasly fue el primero en tener un problema en la temporada 2022 de <a href=\"https:\/\/grandepremio.com\/es\/\/categoria\/f1\/\" target=\"_blank\" rel=\"noreferrer noopener\">F\u00f3rmula 1<\/a>. En la vuelta 46 del GP de Bahrein, el motor del AlphaTauri #10 tuvo una aver\u00eda y, cuando el franc\u00e9s aparc\u00f3 el b\u00f3lido en la pista, se inici\u00f3 un incendio, quem\u00e1ndose la parte trasera del AT03. Al final de la carrera, el equipo evalu\u00f3 que un problema con el motor de recuperaci\u00f3n de energ\u00eda (ERS) fue la causa probable de las llamas en la parte trasera que provocaron la retirada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hermanos Red Bull y AlphaTauri atravesaron momentos dif\u00edciles en el GP de Bahrein. Los coches de Max Verstappen y Sergio P\u00e9rez tuvieron fallos en el sistema de combustible que provocaron la retirada de ambos en las \u00faltimas vueltas. Antes, sin embargo, era el AlphaTauri de Gasly el que ya hab\u00eda presentado el fallo de motor y promovi\u00f3 la entrada del \u00fanico coche de seguridad en Sakhir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong>\u00a1Conoce el canal de Grande Pr\u00eamio en Espa\u00f1ol en\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCDxWojGVUi9gWYhrY0pGbIQ\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube<\/a>!<br>\u00a1Sigue a\u00a0Grande Pr\u00eamio en Espa\u00f1ol\u00a0en\u00a0<a href=\"https:\/\/twitter.com\/grandepremioES\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter\u00a0<\/a>y en\u00a0<a href=\"https:\/\/www.instagram.com\/grandepremioes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>!<\/strong><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2022\/03\/Gasly-Corrida-Bahrein-3-1024x568.jpg\" alt=\"\" class=\"wp-image-551022\"\/><figcaption>Pierre Gasly tuvo que salir saltando del coche en llamas (Reproducci\u00f3n: F1)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la carrera, el piloto franc\u00e9s afirm\u00f3 que el coche simplemente dej\u00f3 de funcionar sin previo aviso. &#8220;Literalmente, no me informaron, lo cual es muy extra\u00f1o&#8221;, revel\u00f3 en una entrevista con la revista inglesa Autosport.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el AlphaTauri carbonizado de vuelta en el garaje, el personal t\u00e9cnico del equipo inspeccion\u00f3 el coche y, seg\u00fan el director t\u00e9cnico Jody Egginton, un problema con el motor de recuperaci\u00f3n de energ\u00eda (ERS) podr\u00eda ser la raz\u00f3n por la cual el motor se par\u00f3. \u201cFue un fallo instant\u00e1neo, una p\u00e9rdida total de energ\u00eda. Por el momento est\u00e1 potencialmente relacionado con la bater\u00eda, no lo sabemos exactamente\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Todav\u00eda estamos investigando. Primero tenemos que encontrar el problema, pero probablemente tendremos que cambiar un elemento de la unidad de potencia&#8221;, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La otra preocupaci\u00f3n de los mec\u00e1nicos son los da\u00f1os causados \u200b\u200bpor el fuego, que pueden promover algunos cambios en los elementos colocados en la parte trasera del coche. &#8220;Todav\u00eda estamos evaluando, pero al menos la suspensi\u00f3n trasera y mucho cableado ser\u00e1n nuevos ya que el carenado se ha quemado&#8221;, dijo Egginton.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.grandepremio.com\/br\/wp-content\/uploads\/2022\/03\/alphatauri-pierregasly-01-4-1024x683.jpg\" alt=\"\" class=\"wp-image-551208\"\/><figcaption>Pierre Gasly sali\u00f3 sin puntos del GP de Bahrein (Foto: AlphaTauri)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEvaluaremos la bater\u00eda y el sistema de recuperaci\u00f3n de energ\u00eda, porque hay mucho material extinto en el coche. En el peor de los casos es un elemento de la unidad de potencia y un elemento del chasis, pero de momento es pronto para decirlo\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si se trata de un desperfecto en el ERS, AlphaTauri se enfrentar\u00e1 a una complicaci\u00f3n importante: si es necesaria la sustituci\u00f3n del elemento, el equipo deber\u00e1 realizar la primera sustituci\u00f3n de las dos permitidas reglamentariamente en la segunda de las 21 carreras confirmadas para la temporada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AlphaTauri cree que es probable que el ERS (motor de recuperaci\u00f3n de energ\u00eda) causara el incendio en la parte trasera de coche de Gasly.<\/p>\n","protected":false},"author":0,"featured_media":1010057100,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[5],"tags":[2391,508,1092,181,1495,179,2315,1195,2390,427,1095],"42wp_author":[14233],"class_list":["post-23825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f1","tag-abandono","tag-alphatauri","tag-bahrein","tag-f1","tag-f1-2022","tag-formula-1","tag-gp-de-bahrein-2","tag-incendio","tag-jody-egginton","tag-pierre-gasly","tag-sakhir","42wp_author-eric-calduch"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/posts\/23825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/comments?post=23825"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/posts\/23825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/media\/1010057100"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/media?parent=23825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/categories?post=23825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/tags?post=23825"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/42wp_author?post=23825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}