{"id":4811,"date":"2025-10-13T10:01:04","date_gmt":"2025-10-13T13:01:04","guid":{"rendered":"https:\/\/grandepremio.com\/es\/2025\/10\/13\/antonelli-admite-cambio-estilo-pilotaje-adaptarse-f1-2025\/"},"modified":"2025-10-13T10:01:09","modified_gmt":"2025-10-13T13:01:09","slug":"antonelli-admite-cambio-estilo-pilotaje-adaptarse-f1-2025","status":"publish","type":"post","link":"https:\/\/grandepremio.com\/es\/f1\/antonelli-admite-cambio-estilo-pilotaje-adaptarse-f1-2025\/","title":{"rendered":"Antonelli admite cambio de estilo de pilotaje para adaptarse a la F1: \u00abNo es natural\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Andrea Kimi Antonelli<\/strong> consider\u00f3 que su estilo de conducci\u00f3n agresivo no se adapta a las caracter\u00edsticas de la generaci\u00f3n actual de monoplazas de <strong>F\u00f3rmula 1<\/strong> y admiti\u00f3 que ha estado haciendo ajustes para adaptarse. Para el novato de <strong>Mercedes<\/strong>, los coches actuales son extremadamente sensibles y castigan cualquier exceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El l\u00edmite es tan alto que, una vez que lo superas, no hay forma de recuperarse. Una vez que lo superas, no tienes nada, es muy impredecible y dif\u00edcil de controlar&#8221;, declar\u00f3 el italiano tras el <strong>Gran Premio de Singapur<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El italiano enfatiz\u00f3 que a\u00fan busca un equilibrio entre confianza y control, especialmente en curvas de alta velocidad antes de que cambie el reglamento t\u00e9cnico de la categor\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udfe5&nbsp;<strong><em>\u00a1Todas las novedades te esperan en el canal de&nbsp;<\/em><\/strong><a href=\"https:\/\/www.youtube.com\/@GrandePremioES\"><em>YouTube<\/em><\/a><strong><em>&nbsp;de Grande Pr\u00eamio en Espa\u00f1ol!<\/em><\/strong>&nbsp;\ud83d\udfe8<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/grandepremio.com\/es\/wp-content\/uploads\/..\/gp_br_uploads\/2025\/10\/singapura-2025-f1-classificacao-mercedes-kimi-antonelli-03.jpg\" alt=\"\" class=\"wp-image-368002\"\/><figcaption class=\"wp-element-caption\">Andrea Kimi Antonelli se\u00f1al\u00f3 que busca adaptar su estilo de manejo al F1 actual. (Foto: Mercedes)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u23e9\u00a0<strong><em>\u00a1Seguinos en redes por\u00a0<\/em><\/strong><a href=\"https:\/\/twitter.com\/grandepremioES\"><em>Twitter\u00a0<\/em><\/a><strong><em>e\u00a0<\/em><\/strong><a href=\"https:\/\/www.instagram.com\/grandepremioes\/\"><em>Instagram!<br><\/em><\/a>\u23e9\u00a0<strong><em>Adem\u00e1s, tenemos nuestro\u00a0<\/em><\/strong><a href=\"https:\/\/whatsapp.com\/channel\/0029VaDZ5zb0gcfDxuwxBM05\"><em>canal de Whatsapp<\/em><\/a><strong><em>\u00a0con toda la informaci\u00f3n al instante<\/em><\/strong>\u00a0\ud83c\udfc1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Sigo sintiendo que no puedo conducir el coche como quiero. Mi estilo es bastante agresivo, y creo que lo vieron en algunas ocasiones, como en <strong>Monza<\/strong>, cuando tiendo a lanzar el coche en las curvas&#8221;, record\u00f3, citando el incidente en el que hizo un trompo y provoc\u00f3 una bandera roja tras quedarse atascado en la grava durante la FP2 del <strong>Gran Premio de Italia<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Parece que con esta generaci\u00f3n de coches no se puede hacer eso. Quiz\u00e1s por la forma en que funciona la aerodin\u00e1mica o los neum\u00e1ticos. Son coches muy sensibles&#8221;, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Estoy intentando adaptar un poco mi estilo de conducci\u00f3n, no cambiarlo por completo. En algunas curvas, el coche acepta este estilo, pero en otras no. Se trata de entender d\u00f3nde puedo arriesgarme m\u00e1s y d\u00f3nde debo ser m\u00e1s cuidadoso. Todav\u00eda no es del todo natural, pero estoy mejorando poco a poco&#8221;, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>F\u00f3rmula 1<\/strong>&nbsp;regresa del 17 al 19 de octubre al&nbsp;<strong>Circuito de las Am\u00e9ricas en Austin<\/strong>, sede del&nbsp;<strong>Gran Premio de Estados Unidos<\/strong>, la 19\u00aa ronda de la&nbsp;<strong>temporada 2025<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-gestor-del-servicio wp-block-embed-gestor-del-servicio wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/youtube.com\/watch?v=TqtdgRWwR58%3Fversion%3D3%26rel%3D1%26showsearch%3D0%26showinfo%3D1%26iv_load_policy%3D1%26fs%3D1%26hl%3Des-ES%26autohide%3D2%26wmode%3Dtransparent\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mientras se adapta a la F\u00f3rmula 1, Andrea Kimi Antonelli reconoci\u00f3 que el manejo de los monoplazas actuales requiere mayor precisi\u00f3n y una conducci\u00f3n menos agresiva. El italiano explic\u00f3 que a\u00fan intenta encontrar el equilibrio entre confianza y control para aplicar su estilo sin exceder los l\u00edmites en el Mercedes.<\/p>\n","protected":false},"author":0,"featured_media":1010367881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"42wp_featured_image_caption":"","42wp_featured_image_credits":"","42wp_featured_video":"","42wp_featured_image_hidden":false,"42wp_authors_list":[],"footnotes":""},"categories":[5],"tags":[6800,1710,179,197,11524],"42wp_author":[14240],"class_list":["post-4811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f1","tag-andrea-kimi-antonelli","tag-f1-2025","tag-formula-1","tag-mercedes","tag-w16","42wp_author-ignacio-bogado"],"_links":{"self":[{"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/posts\/4811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/comments?post=4811"}],"version-history":[{"count":0,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/posts\/4811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/media\/1010367881"}],"wp:attachment":[{"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/media?parent=4811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/categories?post=4811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/tags?post=4811"},{"taxonomy":"42wp_author","embeddable":true,"href":"https:\/\/grandepremio.com\/es\/wp-json\/wp\/v2\/42wp_author?post=4811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}